{"id":1468,"date":"2014-06-20T09:08:20","date_gmt":"2014-06-20T07:08:20","guid":{"rendered":"http:\/\/abenteuer-siedeln.de\/blog\/?p=1468"},"modified":"2014-06-20T09:23:31","modified_gmt":"2014-06-20T07:23:31","slug":"siedlerwetter","status":"publish","type":"post","link":"https:\/\/abenteuer-siedeln.de\/blog\/siedlerwetter\/","title":{"rendered":"Siedlerwetter"},"content":{"rendered":"<p>Beinahe w\u00e4ren wir vom Wetter entt\u00e4uscht gewesen. Vielleicht erinnert sich der eine oder andere noch an die Bilder vom Abenteuer Siedeln 2010, bei dem wir drei Tage Regenwetter und eine wirkliche Schlammschlacht auf dem Zeltplatz zu bew\u00e4ltigen hatten. Diesmal war zum Gl\u00fcck die Lage ganz anders.<\/p>\n<p>Wir hatten bisher knapp drei Tage bestes Sommerwetter. Nicht zu hei\u00df, aber immer trocken. Erst am Donnerstagnachmittag hat uns eine Gewitterfront eine halbe Stunde heftigen Regen beschert. Das Wasser scho\u00df wie aus Eimern die Zeltw\u00e4nde herab. Unser Gl\u00fcck: kurz vorher haben wir die Bewertung der Tagesaufgabe &#8222;Hochspannung&#8220; \u00fcber die B\u00fchne gebracht. Mit den ersten Regentropfen beendete die letzte Zeltstadt gerade noch halbwegs trocken ihre Darbietung. Mehr zu den Tagesaufgaben schreiben wir in einem eigenen Blog-Beitrag.<\/p>\n<p>Der Stimmung tat das keinen Abbruch. Zum Abendessen war der Spuk vorbei. Alle Zelte sind innen halbwegs trocken geblieben und wir konnten uns auf die Siedler-Disco am Donnerstagabend und das Volksfest und den Abschlussabend am Freitag freuen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beinahe w\u00e4ren wir vom Wetter entt\u00e4uscht gewesen. Vielleicht erinnert sich der eine oder andere noch an die Bilder vom Abenteuer Siedeln 2010, bei dem wir drei Tage Regenwetter und eine wirkliche Schlammschlacht auf dem Zeltplatz zu bew\u00e4ltigen hatten. Diesmal war&hellip; <\/p>\n","protected":false},"author":1,"featured_media":1471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/posts\/1468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/comments?post=1468"}],"version-history":[{"count":4,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/posts\/1468\/revisions"}],"predecessor-version":[{"id":1473,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/posts\/1468\/revisions\/1473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/media\/1471"}],"wp:attachment":[{"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/media?parent=1468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/categories?post=1468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abenteuer-siedeln.de\/blog\/wp-json\/wp\/v2\/tags?post=1468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}